{"id":17207,"date":"2023-12-26T18:47:04","date_gmt":"2023-12-26T11:47:04","guid":{"rendered":"https:\/\/sem.hust.edu.vn\/?post_type=lecturers&#038;p=17207"},"modified":"2024-06-20T14:01:03","modified_gmt":"2024-06-20T07:01:03","slug":"m-a-nguyen-thi-yen","status":"publish","type":"lecturers","link":"https:\/\/sem.hust.edu.vn\/en\/lecturers\/m-a-nguyen-thi-yen","title":{"rendered":"M.S. Nguyen Thi Yen"},"content":{"rendered":"<p>Master at Vietnam National University<\/p>\n<p>Teaching: Fundamentals of Law<\/p>\n<ul>\n<li>EM1170 &#8211; Principles of Law<\/li>\n<li>EM3222 &#8211; Business Law<\/li>\n<\/ul>\n<p>Academic Database:<\/p>\n<ul>\n<li>ISSN 0866-7756<\/li>\n<\/ul>\n<p>Research Orientation:<\/p>\n<ul>\n<li>Sustainable Development<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Lecturer<\/p>","protected":false},"featured_media":17208,"parent":0,"template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set"},"chuyen-muc-giang-vien":[186,110],"class_list":["post-17207","lecturers","type-lecturers","status-publish","has-post-thumbnail","hentry","chuyen-muc-giang-vien-lecturers","chuyen-muc-giang-vien-the-research-authors"],"acf":[],"aioseo_notices":[],"uagb_featured_image_src":{"full":["https:\/\/sem.hust.edu.vn\/wp-content\/uploads\/2023\/12\/Ths-Yen-Nguyen.jpeg",354,472,false],"thumbnail":["https:\/\/sem.hust.edu.vn\/wp-content\/uploads\/2023\/12\/Ths-Yen-Nguyen-150x150.jpeg",150,150,true],"medium":["https:\/\/sem.hust.edu.vn\/wp-content\/uploads\/2023\/12\/Ths-Yen-Nguyen-225x300.jpeg",225,300,true],"medium_large":["https:\/\/sem.hust.edu.vn\/wp-content\/uploads\/2023\/12\/Ths-Yen-Nguyen.jpeg",354,472,false],"large":["https:\/\/sem.hust.edu.vn\/wp-content\/uploads\/2023\/12\/Ths-Yen-Nguyen.jpeg",354,472,false],"1536x1536":["https:\/\/sem.hust.edu.vn\/wp-content\/uploads\/2023\/12\/Ths-Yen-Nguyen.jpeg",354,472,false],"2048x2048":["https:\/\/sem.hust.edu.vn\/wp-content\/uploads\/2023\/12\/Ths-Yen-Nguyen.jpeg",354,472,false],"trp-custom-language-flag":["https:\/\/sem.hust.edu.vn\/wp-content\/uploads\/2023\/12\/Ths-Yen-Nguyen.jpeg",9,12,false],"menu-24x24":["https:\/\/sem.hust.edu.vn\/wp-content\/uploads\/2023\/12\/Ths-Yen-Nguyen-18x24.jpeg",18,24,true],"menu-36x36":["https:\/\/sem.hust.edu.vn\/wp-content\/uploads\/2023\/12\/Ths-Yen-Nguyen-27x36.jpeg",27,36,true],"menu-48x48":["https:\/\/sem.hust.edu.vn\/wp-content\/uploads\/2023\/12\/Ths-Yen-Nguyen-36x48.jpeg",36,48,true]},"uagb_author_info":{"display_name":"sem editor","author_link":"https:\/\/sem.hust.edu.vn\/en\/author"},"uagb_comment_info":0,"uagb_excerpt":"Lecturer","_links":{"self":[{"href":"https:\/\/sem.hust.edu.vn\/en\/wp-json\/wp\/v2\/lecturers\/17207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sem.hust.edu.vn\/en\/wp-json\/wp\/v2\/lecturers"}],"about":[{"href":"https:\/\/sem.hust.edu.vn\/en\/wp-json\/wp\/v2\/types\/lecturers"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sem.hust.edu.vn\/en\/wp-json\/wp\/v2\/media\/17208"}],"wp:attachment":[{"href":"https:\/\/sem.hust.edu.vn\/en\/wp-json\/wp\/v2\/media?parent=17207"}],"wp:term":[{"taxonomy":"chuyen-muc-giang-vien","embeddable":true,"href":"https:\/\/sem.hust.edu.vn\/en\/wp-json\/wp\/v2\/chuyen-muc-giang-vien?post=17207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}